{"id":1,"count":2,"description":"","link":"http:\/\/www.rusrim.com\/bg\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.rusrim.com\/bg\/wp-json\/wp\/v2\/categories\/1"}],"collection":[{"href":"http:\/\/www.rusrim.com\/bg\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.rusrim.com\/bg\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.rusrim.com\/bg\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}